{"id":342715,"date":"2023-09-26T14:06:01","date_gmt":"2023-09-26T14:06:01","guid":{"rendered":"http:\/\/relaunch.elten.com.w01ca985.kasserver.com\/?post_type=portfolio&#038;p=402"},"modified":"2026-05-07T10:21:26","modified_gmt":"2026-05-07T10:21:26","slug":"easy-blue-esd-s1-72178","status":"publish","type":"portfolio","link":"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/","title":{"rendered":"EASY blue ESD S1 &#8211; 72178"},"content":{"rendered":"<p><div id='product-details'  class='avia-section av-9o479e-23b1946e314378b5c10e62c895481d4e main_color avia-section-default avia-no-shadow  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-342715'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9kw3h6-b8da2ef29d677bcc7cb4446127eb0b16\">\n.flex_column.av-9kw3h6-b8da2ef29d677bcc7cb4446127eb0b16{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\nbackground-color:#ffffff;\n}\n<\/style>\n<div  class='flex_column av-9kw3h6-b8da2ef29d677bcc7cb4446127eb0b16 av_three_fifth  avia-builder-el-1  el_before_av_two_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9avqhe-f7931d4f34d0d02f5fe7b06cbdeb0a45\">\n.avia-image-container.av-9avqhe-f7931d4f34d0d02f5fe7b06cbdeb0a45 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-9avqhe-f7931d4f34d0d02f5fe7b06cbdeb0a45 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-9avqhe-f7931d4f34d0d02f5fe7b06cbdeb0a45 av-styling-no-styling avia-align-center  avia-builder-el-2  el_before_av_gallery  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-233743 avia-img-lazy-loading-not-233743 avia_image ' src=\"https:\/\/elten.com\/wp-content\/uploads\/2023\/09\/ELTEN-Logo.png\" alt='ELTEN-Logo' title='ELTEN-Logo'  height=\"46\" width=\"147\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-x9ple-82c4ab56f6cd32995d1721b1a265f3d2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><div id='ggpkg_container_0_342715' style='width:100%; height:480px; position: relative;'>\nLoading...\n<\/div>\n<script type='text\/javascript' src='https:\/\/elten.com\/wp-content\/uploads\/360\/72178\/object2vr_player.js'><\/script>\n<script type='text\/javascript' src='https:\/\/elten.com\/wp-content\/uploads\/360\/72178\/skin.js'><\/script>\n<script type='text\/javascript'>\nwindow.addEventListener('load',function() {\nif  (typeof _72178_object2vrPlayer != 'undefined') {\n\tobj_0_342715=new _72178_object2vrPlayer('ggpkg_container_0_342715');\n} else {\n\tobj_0_342715=new object2vrPlayer('ggpkg_container_0_342715');\n}\nif  (typeof _72178_object2vrSkin != 'undefined') {\n\tskin_0_342715=new _72178_object2vrSkin(obj_0_342715, 'https:\/\/elten.com\/wp-content\/uploads\/360\/72178\/');\n} else {\n\tskin_0_342715=new object2vrSkin(obj_0_342715, 'https:\/\/elten.com\/wp-content\/uploads\/360\/72178\/');\n}\nobj_0_342715.readConfigUrl('https:\/\/elten.com\/wp-content\/uploads\/360\/72178\/object.xml');\nvar contentOverflow = document.getElementById('content') ? document.getElementById('content').style.overflow : '';\nobj_0_342715.addListener('fullscreenenter', function() {\n\tif (document.getElementById('content')) {\n\t\tdocument.getElementById('content').style.overflow = 'visible';\n\t}\n});\nobj_0_342715.addListener('fullscreenexit', function() {\n\tif (document.getElementById('content')) {\n\t\tdocument.getElementById('content').style.overflow = contentOverflow;\n\t}\n});\n\n});\n<\/script>\n\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8yqnwy-71032238216ab5acf8961b5dde2ea1af\">\n#top .avia-gallery.av-8yqnwy-71032238216ab5acf8961b5dde2ea1af .avia-gallery-thumb a{\nwidth:12.5%;\n}\n<\/style>\n<div  class='avia-gallery av-8yqnwy-71032238216ab5acf8961b5dde2ea1af avia_animate_when_visible  avia-builder-el-3  el_after_av_image  el_before_av_codeblock  deactivate_avia_lazyload avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/\"><div class='avia-gallery-thumb'><a href=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-01.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/elten.com\/wp-content\/uploads\/products\/72178-01.jpg' class='first_thumb lightbox ' data-onclick='1' title='EASY blue ESD S1 - 72178'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-368079 avia-img-lazy-loading-not-368079\"   src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-01.jpg\" width=\"1\" height=\"1\"  title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-368079 avia-img-lazy-loading-368079\"  width=\"1\" height=\"1\" src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-01.jpg\" title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><\/div><\/a><a href=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-10.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/elten.com\/wp-content\/uploads\/products\/72178-10.jpg' class='lightbox ' data-onclick='2' title='EASY blue ESD S1 - 72178'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-302926 avia-img-lazy-loading-not-302926\"   src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-10.jpg\" width=\"1\" height=\"1\"  title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-302926 avia-img-lazy-loading-302926\"  width=\"1\" height=\"1\" src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-10.jpg\" title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><\/div><\/a><a href=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-20.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/elten.com\/wp-content\/uploads\/products\/72178-20.jpg' class='lightbox ' data-onclick='3' title='EASY blue ESD S1 - 72178'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-302934 avia-img-lazy-loading-not-302934\"   src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-20.jpg\" width=\"1\" height=\"1\"  title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-302934 avia-img-lazy-loading-302934\"  width=\"1\" height=\"1\" src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-20.jpg\" title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><\/div><\/a><a href=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-30.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/elten.com\/wp-content\/uploads\/products\/72178-30.jpg' class='lightbox ' data-onclick='4' title='EASY blue ESD S1 - 72178'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-302942 avia-img-lazy-loading-not-302942\"   src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-30.jpg\" width=\"1\" height=\"1\"  title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-302942 avia-img-lazy-loading-302942\"  width=\"1\" height=\"1\" src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-30.jpg\" title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><\/div><\/a><a href=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-40.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/elten.com\/wp-content\/uploads\/products\/72178-40.jpg' class='lightbox ' data-onclick='5' title='EASY blue ESD S1 - 72178'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-302950 avia-img-lazy-loading-not-302950\"   src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-40.jpg\" width=\"1\" height=\"1\"  title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-302950 avia-img-lazy-loading-302950\"  width=\"1\" height=\"1\" src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-40.jpg\" title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><\/div><\/a><a href=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-50.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/elten.com\/wp-content\/uploads\/products\/72178-50.jpg' class='lightbox ' data-onclick='6' title='EASY blue ESD S1 - 72178'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-302958 avia-img-lazy-loading-not-302958\"   src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-50.jpg\" width=\"1\" height=\"1\"  title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-302958 avia-img-lazy-loading-302958\"  width=\"1\" height=\"1\" src=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-50.jpg\" title='EASY blue ESD S1 - 72178' alt='EASY blue ESD S1 - 72178' \/><\/div><\/a><\/div><\/div><br \/>\n<\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8qxyz6-927c3f65d7a092893f1f61de959aabda\">\n.flex_column.av-8qxyz6-927c3f65d7a092893f1f61de959aabda{\nborder-radius:0px 0px 0px 0px;\npadding:10px 10px 10px 10px;\nbackground-color:#ffffff;\n}\n<\/style>\n<div  class='flex_column av-8qxyz6-927c3f65d7a092893f1f61de959aabda av_two_fifth  avia-builder-el-5  el_after_av_three_fifth  el_before_av_three_fifth  flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8kw2ua-5623ae2a7583822cf5f956f3ec008744\">\n#top .av-special-heading.av-8kw2ua-5623ae2a7583822cf5f956f3ec008744{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-8kw2ua-5623ae2a7583822cf5f956f3ec008744 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-8kw2ua-5623ae2a7583822cf5f956f3ec008744 .av-subheading{\nfont-size:12px;\n}\n<\/style>\n<div  class='av-special-heading av-8kw2ua-5623ae2a7583822cf5f956f3ec008744 av-special-heading-h2 blockquote modern-quote  avia-builder-el-6  el_before_av_hr  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >72178 &#8211; EASY blue ESD S1<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='hr av-8eyqaa-29625338bc39349b3606f805a2ace7ec hr-default  avia-builder-el-7  el_after_av_heading  el_before_av_codeblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<br \/>\n<div  class='hr av-t0kh6-65d7b244cc07d23b655556227d19ced9 hr-default  avia-builder-el-9  el_after_av_codeblock  el_before_av_button_big  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7pxqbu-3a9af0464f413ecd93493cb12a3dd05b\">\n#top .hr.hr-invisible.av-7pxqbu-3a9af0464f413ecd93493cb12a3dd05b{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-7pxqbu-3a9af0464f413ecd93493cb12a3dd05b hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-10  el_after_av_hr  el_before_av_hr '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7hbby2-3e5f74077e353fae6f0c2031af5724b7\">\n#top #wrap_all .avia-button.av-7hbby2-3e5f74077e353fae6f0c2031af5724b7{\nbackground-color:#000000;\nborder-color:#000000;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-7hbby2-3e5f74077e353fae6f0c2031af5724b7:hover{\nbackground-color:#000000;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/elten.com\/pl\/grupy-produktow\/trainers' class='avia-font-color-theme-color avia-button avia-button-fullwidth av-7hbby2-3e5f74077e353fae6f0c2031af5724b7 avia-icon_select-no avia-color-custom'  ><span class='avia_iconbox_title' >Dowiedz si\u0119 wi\u0119cej o tej linii produkt\u00f3w<\/span><\/a><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7bwhaa-5b4b31c826505a054b99eb0c6c3f7b8c\">\n#top .hr.hr-invisible.av-7bwhaa-5b4b31c826505a054b99eb0c6c3f7b8c{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-7bwhaa-5b4b31c826505a054b99eb0c6c3f7b8c hr-invisible  avia-builder-el-11  el_after_av_button_big  el_before_av_button_big  avia-builder-el-no-sibling '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-12  el_after_av_hr  el_before_av_hr '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7687w2-1df51385eaecb51cd6cc82d46b9ad2fa\">\n#top #wrap_all .avia-button.av-7687w2-1df51385eaecb51cd6cc82d46b9ad2fa{\nbackground-color:#000000;\nborder-color:#000000;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-7687w2-1df51385eaecb51cd6cc82d46b9ad2fa:hover{\nbackground-color:#000000;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/elten.com\/pl\/podaj-zrodla-zaopatrzenia\/?text-artikelnummer=72178' class='avia-font-color-theme-color avia-button avia-button-fullwidth av-7687w2-1df51385eaecb51cd6cc82d46b9ad2fa avia-icon_select-no avia-color-custom'  ><span class='avia_iconbox_title' >Podaj \u017ar\u00f3d\u0142a zaopatrzenia<\/span><\/a><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-725wwy-94922a054ba90474fa86f7a58b02814d\">\n#top .hr.hr-invisible.av-725wwy-94922a054ba90474fa86f7a58b02814d{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-725wwy-94922a054ba90474fa86f7a58b02814d hr-invisible  avia-builder-el-13  el_after_av_button_big  el_before_av_button_big  avia-builder-el-no-sibling  trd-to-pdf-button'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6uirtm-96040fffc970274fa72b84a8421c33a0\">\n#top .hr.hr-invisible.av-6uirtm-96040fffc970274fa72b84a8421c33a0{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-6uirtm-96040fffc970274fa72b84a8421c33a0 hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='av-social-sharing-box av-obz16-705f50970d6caa75a52d771d39d7e2ae av-social-sharing-box-minimal av-social-sharing-box-fullwidth'><div class=\"av-share-box\"><h5 class='av-share-link-description av-no-toc '>Przekaz innym<\/h5><ul class=\"av-share-box-list noLightbox\"><li class='av-share-link av-social-link-facebook' ><a target=\"_blank\" aria-label=\"Udost\u0119pnij Facebook\" href='https:\/\/www.facebook.com\/sharer.php?u=https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/&#038;t=EASY%20blue%20ESD%20S1%20%E2%80%93%2072178' aria-hidden='false' data-av_icon='\ue8f3' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Udost\u0119pnij Facebook' rel=\"noopener\"><span class='avia_hidden_link_text'>Udost\u0119pnij Facebook<\/span><\/a><\/li><li class='av-share-link av-social-link-twitter' ><a target=\"_blank\" aria-label=\"Udost\u0119pnij Twitter\" href='https:\/\/twitter.com\/share?text=EASY%20blue%20ESD%20S1%20%E2%80%93%2072178&#038;url=https:\/\/elten.com\/pl\/?p=342715' aria-hidden='false' data-av_icon='\ue932' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Udost\u0119pnij Twitter' rel=\"noopener\"><span class='avia_hidden_link_text'>Udost\u0119pnij Twitter<\/span><\/a><\/li><li class='av-share-link av-social-link-whatsapp' ><a target=\"_blank\" aria-label=\"Share on WhatsApp\" href='https:\/\/api.whatsapp.com\/send?text=https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/' aria-hidden='false' data-av_icon='\uf232' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Share on WhatsApp' rel=\"noopener\"><span class='avia_hidden_link_text'>Share on WhatsApp<\/span><\/a><\/li><li class='av-share-link av-social-link-pinterest' ><a target=\"_blank\" aria-label=\"Udost\u0119pnij Pinterest\" href='https:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Felten.com%2Fpl%2Fproducts%2Feasy-blue-esd-s1-72178%2F&#038;description=EASY%20blue%20ESD%20S1%20%E2%80%93%2072178&#038;media=https%3A%2F%2Felten.com%2Fwp-content%2Fuploads%2Fproducts%2F72178-01.jpg' aria-hidden='false' data-av_icon='\ue8f8' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Udost\u0119pnij Pinterest' rel=\"noopener\"><span class='avia_hidden_link_text'>Udost\u0119pnij Pinterest<\/span><\/a><\/li><li class='av-share-link av-social-link-mail' ><a  aria-label=\"Wy\u015blij e-mail\" href='mailto:?subject=EASY%20blue%20ESD%20S1%20%E2%80%93%2072178&#038;body=https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/' aria-hidden='false' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Wy\u015blij e-mail'><span class='avia_hidden_link_text'>Wy\u015blij e-mail<\/span><\/a><\/li><\/ul><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6lad02-8d55f19fa37d4a310f08cf70f553e967\">\n#top .hr.hr-invisible.av-6lad02-8d55f19fa37d4a310f08cf70f553e967{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-6lad02-8d55f19fa37d4a310f08cf70f553e967 hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6ep9ia-222683c66b91e4e9be4cbe52b8715a00\">\n.flex_column.av-6ep9ia-222683c66b91e4e9be4cbe52b8715a00{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\nbackground-color:#ffffff;\n}\n<\/style>\n<div  class='flex_column av-6ep9ia-222683c66b91e4e9be4cbe52b8715a00 av_three_fifth first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-69rzka-bef9d068479f5c646e2c15754c87aaf1\">\n#top .hr.hr-invisible.av-69rzka-bef9d068479f5c646e2c15754c87aaf1{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-69rzka-bef9d068479f5c646e2c15754c87aaf1 hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='tabcontainer av-5z4ggq-29a5885d9d286dcf0d342f6c94516546 top_tab' role='tablist'>\n<section class='av_tab_section av_tab_section av-5uk8fe-038b735ab68a9fa28d1aaa60b6fffd7b'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab active_tab' role='tab' tabindex='0' data-fake-id='#tab-id-1' aria-controls='tab-id-1-content'  itemprop=\"headline\" >Nasza opinia<\/div><div id='tab-id-1-content' class='tab_content active_tab_content' aria-hidden=\"false\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><ul>\n<li>Materia\u0142 mesh\/Materia\u0142 tekstylny<\/li>\n<li>Podszewka tekstylna aktywnie przepuszczaj\u0105ca powietrze<\/li>\n<li>J\u0119zyk wy\u015bcie\u0142any<\/li>\n<li>ca\u0142opowierzchniowa wk\u0142adka ESD PRO grey z zawarto\u015bci\u0105 materia\u0142\u00f3w pochodz\u0105cych z recyklingu<\/li>\n<li>Podpodeszwa antyelektrostatyczna z mi\u0119kkiej w\u0142\u00f3kniny (softvlies) spe\u0142niaj\u0105ca wymagania w zakresie wy\u0142adowa\u0144 elektrostatycznych (ESD)<\/li>\n<li>Podeszwa TPU\/PU TRAINERS<\/li>\n<li>Podnosek z metalu<\/li>\n<li>EN ISO 20345:2022 S1 FO\/SR, typ A (p\u00f3\u0142buty)<\/li>\n<li>Bez u\u017cycia sk\u00f3ry<\/li>\n<\/ul>\n<\/div><\/div><\/section>\n<section class='av_tab_section av_tab_section av-5s1z76-5fb7166b6176e818a45fea49f16951b2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab' role='tab' tabindex='0' data-fake-id='#tab-id-2' aria-controls='tab-id-2-content'  itemprop=\"headline\" >Details<\/div><div id='tab-id-2-content' class='tab_content' aria-hidden=\"true\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><div class=\"shoeDetailFurtherInfo\"><\/div>\n<\/div><\/div><\/section>\n<section class='av_tab_section av_tab_section av-lzgsgpnn-aa59de524d00531ac59d58dd9cc60dfe'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab' role='tab' tabindex='0' data-fake-id='#tab-id-3' aria-controls='tab-id-3-content'  itemprop=\"headline\" >Orto \/ wk\u0142adek<\/div><div id='tab-id-3-content' class='tab_content' aria-hidden=\"true\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><h5 class=\"inlay_mb\">Certyfikowany dla nast\u0119puj\u0105cego wyposa\u017cenia ortopedycznego zgodnie z norm\u0105 EN ISO 20345\/20347 (DGUV 112-191)<\/h5>\n<ul>\n<li><a href=\"https:\/\/elten.com\/pl\/manufacturing-instructions\/\">Wk\u0142adki<\/a><\/li>\n<li><a href=\"https:\/\/elten.com\/pl\/manufacturing-instructions\/\">Dostosowanie<\/a><\/li>\n<\/ul>\n<h5 class=\"inlay_mb\">Certyfikowane wk\u0142adki \/ ortezy<\/h5>\n<ul>\n<li>ESD Pro<\/li>\n<li>Bauerfeind Ergo Pad Work:H<\/li>\n<li>Hartmann 9516 Secosol<\/li>\n<li>Mander-Malms SoftAstatic SAV-02<\/li>\n<li>Mander-Malms SoftAstatic SA PUR-02<\/li>\n<li>Seidl Sensoped ESD 3596<\/li>\n<\/ul>\n<h5 class=\"inlay_mb\">Akcesoria<\/h5>\n<ul>\n<li>SensiCare<\/li>\n<li>ARTISAN<\/li>\n<li>ARTISAN Yellow<\/li>\n<li>Currex Work Pro<\/li>\n<\/ul>\n<\/div><\/div><\/section><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5hv3my-6c3b65a059f22f64adbc21e0c5519f76\">\n.flex_column.av-5hv3my-6c3b65a059f22f64adbc21e0c5519f76{\nborder-radius:0px 0px 0px 0px;\npadding:10px 10px 10px 10px;\nbackground-color:#ffffff;\n}\n<\/style>\n<div  class='flex_column av-5hv3my-6c3b65a059f22f64adbc21e0c5519f76 av_two_fifth flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5dnacy-5444c3733872617e5d2d7956bfcb72e5\">\n#top .hr.hr-invisible.av-5dnacy-5444c3733872617e5d2d7956bfcb72e5{\nheight:28px;\n}\n<\/style>\n<div  class='hr av-5dnacy-5444c3733872617e5d2d7956bfcb72e5 hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<br \/>\n<div  class='avia-logo-element-container av-501pcy-a92339e498fe04f1d9f6aad0a8821ba9 av-border-deactivate avia-logo-grid avia-content-slider avia-smallarrow-slider avia-content-grid-active noHover avia-content-slider-odd  el-bg-weiss avia-content-slider1' ><div class='avia-smallarrow-slider-heading  no-logo-slider-heading '><div class='new-special-heading'>&nbsp;<\/div><\/div><div class=\"avia-content-slider-inner\"><div class=\"slide-entry-wrap\"><div data-avia-tooltip=\"ESD: Obuwie ochronne i obuwie robocze posiadajace certyfikat ESD nie tylko chroni personel, ale r\u00f3wniez zapewnia ochrone zagrozonych element\u00f3w i podzespol\u00f3w przed energia elektrostatyczna.\" class='slide-entry av-av_partner_logo-65563ecab7484714e8e35d610b0122bf flex_column no_margin av_one_fifth real-thumbnail post-entry slide-entry-overview slide-loop-1 slide-parity-odd  first'><a href=\"https:\/\/elten.com\/pl\/technologia\/piktogramy\/\" data-rel='slide-1' class='slide-image' title=''  target=\"_blank\"  rel=\"noopener noreferrer\"><span class='av-partner-fake-img' style='padding-bottom:100%; background-image:url(https:\/\/elten.com\/wp-content\/uploads\/2023\/09\/0100.jpg);'><\/span><\/a><\/div><div data-avia-tooltip=\"ORTOPEDYCZNA OCHRONA ST\u00d3P: But jest certyfikowany do modyfikacji ortopedycznych zgodnie z regula DGUV 112-191. Tw\u00f3j zaufany szewc ortopedyczny \/ tw\u00f3j zaufany sklep z artykulami medycznymi moze dokonac szeregu zmian ortopedycznych i wkladek, kt\u00f3re spelnia Twoje potrzeby - bez utraty funkcji ochronnej buta.\" class='slide-entry av-av_partner_logo-0994fb5bf74362daced1fc1141720e4b flex_column no_margin av_one_fifth real-thumbnail post-entry slide-entry-overview slide-loop-2 slide-parity-even post-entry-last '><a href=\"https:\/\/elten.com\/pl\/technologia\/piktogramy\/\" data-rel='slide-1' class='slide-image' title=''  target=\"_blank\"  rel=\"noopener noreferrer\"><span class='av-partner-fake-img' style='padding-bottom:100%; background-image:url(https:\/\/elten.com\/wp-content\/uploads\/2023\/09\/4600.jpg);'><\/span><\/a><\/div><\/div><\/div><\/div><\/p><\/div><br \/>\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4pclxm-c43378e37684afca0d63e95c6c2522b2\">\n.avia-section.av-4pclxm-c43378e37684afca0d63e95c6c2522b2{\nbackground-color:#ffffff;\nbackground-image:unset;\n}\n<\/style>\n<div id='product-details-2'  class='avia-section av-4pclxm-c43378e37684afca0d63e95c6c2522b2 main_color avia-section-default avia-no-shadow avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-342715'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4mcv2q-2ed6023d5bd2b4d120d9e7fbe0753a90\">\n.flex_column.av-4mcv2q-2ed6023d5bd2b4d120d9e7fbe0753a90{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-4mcv2q-2ed6023d5bd2b4d120d9e7fbe0753a90 av_one_full first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4gi4nm-d2502773c8f483369f0b598ef423e506\">\n#top .av-special-heading.av-4gi4nm-d2502773c8f483369f0b598ef423e506{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-4gi4nm-d2502773c8f483369f0b598ef423e506 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-4gi4nm-d2502773c8f483369f0b598ef423e506 .av-subheading{\nfont-size:12px;\n}\n<\/style>\n<div  class='av-special-heading av-4gi4nm-d2502773c8f483369f0b598ef423e506 av-special-heading-h3 blockquote modern-quote'><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Pasuj\u0105ce akcesoria<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-496ioq-2f3581347d7728cee6ecd6de22d64d4a\">\n#top .hr.hr-invisible.av-496ioq-2f3581347d7728cee6ecd6de22d64d4a{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-496ioq-2f3581347d7728cee6ecd6de22d64d4a hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-44676a-070ec583c318467fe32d07f6458df25e\">\n.flex_column.av-44676a-070ec583c318467fe32d07f6458df25e{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-44676a-070ec583c318467fe32d07f6458df25e av_one_fifth first flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3nmv2q-8439f27cb4b34174d78cd11ae2b7dbbf\">\n.flex_column.av-3nmv2q-8439f27cb4b34174d78cd11ae2b7dbbf{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3nmv2q-8439f27cb4b34174d78cd11ae2b7dbbf av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-17bq2-2b45d9ba544062f33fe75cffffad39ea\">\n.flex_column.av-17bq2-2b45d9ba544062f33fe75cffffad39ea{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-17bq2-2b45d9ba544062f33fe75cffffad39ea av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-34vg9e-0a46296d237d498bc0eaddb22d04d572\">\n.flex_column.av-34vg9e-0a46296d237d498bc0eaddb22d04d572{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-34vg9e-0a46296d237d498bc0eaddb22d04d572 av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2pousi-7cbe4a523fdfc12bd00335a2c7c942de\">\n.flex_column.av-2pousi-7cbe4a523fdfc12bd00335a2c7c942de{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-2pousi-7cbe4a523fdfc12bd00335a2c7c942de av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_2'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-342715'><div class='entry-content-wrapper clearfix'><br \/>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2f5z4q-29a7b62a102ab33f2e1cfbb6f6500feb\">\n.avia-section.av-2f5z4q-29a7b62a102ab33f2e1cfbb6f6500feb{\nbackground-color:#eeeeee;\nbackground-image:unset;\n}\n<\/style>\n<div id='product-details-3'  class='avia-section av-2f5z4q-29a7b62a102ab33f2e1cfbb6f6500feb main_color avia-section-default avia-no-shadow avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-342715'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-26ahl6-b7dd96b02bc75608f2e143d4d39e6726\">\n.flex_column.av-26ahl6-b7dd96b02bc75608f2e143d4d39e6726{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-26ahl6-b7dd96b02bc75608f2e143d4d39e6726 av_one_full first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-24z196-27e8a67fcdcd9d68cc1cab6a4d4dfaa1\">\n#top .av-special-heading.av-24z196-27e8a67fcdcd9d68cc1cab6a4d4dfaa1{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-24z196-27e8a67fcdcd9d68cc1cab6a4d4dfaa1 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-24z196-27e8a67fcdcd9d68cc1cab6a4d4dfaa1 .av-subheading{\nfont-size:12px;\n}\n<\/style>\n<div  class='av-special-heading av-24z196-27e8a67fcdcd9d68cc1cab6a4d4dfaa1 av-special-heading-h3 blockquote modern-quote'><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Podobne artyku\u0142y<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1vbusq-988cfc14d96791427b60fa606d56ac6d\">\n#top .hr.hr-invisible.av-1vbusq-988cfc14d96791427b60fa606d56ac6d{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-1vbusq-988cfc14d96791427b60fa606d56ac6d hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1s0vma-de79fe0c6c04be0df1f5ad2366f1a2b4\">\n.flex_column.av-1s0vma-de79fe0c6c04be0df1f5ad2366f1a2b4{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1s0vma-de79fe0c6c04be0df1f5ad2366f1a2b4 av_one_fifth first flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1eunuy-594212a4ee1ca56b43c56369ccf83925\">\n.flex_column.av-1eunuy-594212a4ee1ca56b43c56369ccf83925{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1eunuy-594212a4ee1ca56b43c56369ccf83925 av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-148m02-966f218cc25b3881fcc9b3fb67d6ebc4\">\n.flex_column.av-148m02-966f218cc25b3881fcc9b3fb67d6ebc4{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-148m02-966f218cc25b3881fcc9b3fb67d6ebc4 av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-sih8q-e9d1a1f0d343a04ee0f59409f344dd42\">\n.flex_column.av-sih8q-e9d1a1f0d343a04ee0f59409f344dd42{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-sih8q-e9d1a1f0d343a04ee0f59409f344dd42 av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-d0vxu-beb001812e7eae546c36447b4fdc33f5\">\n.flex_column.av-d0vxu-beb001812e7eae546c36447b4fdc33f5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-d0vxu-beb001812e7eae546c36447b4fdc33f5 av_one_fifth flex_column_div av-zero-column-padding  '     ><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_3'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-342715'><div class='entry-content-wrapper clearfix'><script>jQuery( \"[data-fake-id*='#tab-id-2']\" ).css('display', 'none');<\/script><\/p>\n<style>#product-details-3 { display: none !important; }<\/style>\n<p><script>jQuery('a.lightbox').attr('title', '');<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":368065,"comment_status":"open","ping_status":"closed","template":"","tags":[],"portfolio_entries":[6795,6785,6787,6788,6789,6651,6652,6653,6654,6659,6102,6103,6107,6112,6114,6094,4833,4868,4835,4813,4814,4818,2322,2323,2324,2325,2254,2255,2256,2257,2258,2259,2260,2261,2262,2284,2312,2429,2296,2272,2274,2276,2332,2250,2318,2430,2278,2469],"absatz":[2277],"dguv":[2279],"esd":[2273],"farbe":[4820],"futter":[2333],"geschlecht":[4815,4816],"groesse":[2326,2327,2328,2329,2263,2264,2265,2266,2267,2268,2269,2270,2271],"metallfrei":[2275],"schuhform":[4843],"schutzklasse":[2319],"tatigkeit":[],"verschluss":[4819],"passform_herren_exporte":[4834],"passform_damen_exporte":[4836],"ausstattung_exporte":[6109],"style_exporte":[6115],"marke":[2313],"verschluss_exporte":[5722],"obermaterial_exporte":[6113],"laufsohlenmaterial_exporte":[4869],"einlegesohlen_exporte":[6796,6792,6793,6794,6790,6655,6656,6657,6658,6660],"norm-bezeichnung":[2297],"uidnachhaltig":[],"uidsmart":[],"uidveredelung":[],"produktgruppe":[4946],"durchtrittschutz_exporte":[7099],"zehenschutzkappe_exporte":[6095],"norm-zusaetze":[6104,6105],"class_list":["post-342715","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-10300_bauerfeind-ergo-pad-workh-pl","portfolio_entries-11000_seidl-sensoped-esd-3596-pl","portfolio_entries-50600_currex-work-pro-pl","portfolio_entries-50300_artisan-pl","portfolio_entries-50400_artisan-yellow-pl","portfolio_entries-10700_mander-malms-softastatic-sav-02-pl","portfolio_entries-10800_mander-malms-softastatic-sa-pur-02-pl","portfolio_entries-10100_esd-pro-pl","portfolio_entries-50100_sensicare-pl","portfolio_entries-10600_hartmann-9516-secosol-pl","portfolio_entries-fo-pl","portfolio_entries-sr-pl","portfolio_entries-bez-uzycia-skory-pl","portfolio_entries-material-tekstylny-pl","portfolio_entries-sportowy-pl","portfolio_entries-podnosek-z-metalu-pl","portfolio_entries-mittel-normal-pl","portfolio_entries-tpu-pl","portfolio_entries-weit-pl","portfolio_entries-04-uniseks-pl","portfolio_entries-05-divers-pl","portfolio_entries-sznurowadla-pl","portfolio_entries-03600-pl","portfolio_entries-03700-pl","portfolio_entries-03800-pl","portfolio_entries-03900-pl","portfolio_entries-04000-pl","portfolio_entries-04100-pl","portfolio_entries-04200-pl","portfolio_entries-04300-pl","portfolio_entries-04400-pl","portfolio_entries-04500-pl","portfolio_entries-04600-pl","portfolio_entries-04700-pl","portfolio_entries-04800-pl","portfolio_entries-czarny-pl","portfolio_entries-elten-pl","portfolio_entries-elten-trainers-pl","portfolio_entries-en-iso-20345-pl","portfolio_entries-esd-pl","portfolio_entries-nie-pl","portfolio_entries-obcas-pl","portfolio_entries-podszewka-tekstylna-pl","portfolio_entries-polbuty-pl","portfolio_entries-s1-pl","portfolio_entries-trainers-pl","portfolio_entries-wkladki-i-dostosowanie-pl","portfolio_entries-zadne-pl","absatz-obcas-pl","dguv-wkladki-i-dostosowanie-pl","esd-esd-pl","farbe-czarny-pl","futter-podszewka-tekstylna-pl","geschlecht-04-uniseks-pl","geschlecht-05-divers-pl","groesse-03600-pl","groesse-03700-pl","groesse-03800-pl","groesse-03900-pl","groesse-04000-pl","groesse-04100-pl","groesse-04200-pl","groesse-04300-pl","groesse-04400-pl","groesse-04500-pl","groesse-04600-pl","groesse-04700-pl","groesse-04800-pl","metallfrei-nie-pl","schuhform-polbuty-pl","schutzklasse-s1-pl","verschluss-sznurowadla-pl","passform_herren_exporte-mittel-normal-pl","passform_damen_exporte-weit-pl","ausstattung_exporte-bez-uzycia-skory-pl","style_exporte-sportowy-pl","marke-elten-pl","verschluss_exporte-sznurowadla-pl","obermaterial_exporte-material-tekstylny-pl","laufsohlenmaterial_exporte-tpu-pl","einlegesohlen_exporte-10300_bauerfeind-ergo-pad-workh-pl","einlegesohlen_exporte-50600_currex-work-pro-pl","einlegesohlen_exporte-50300_artisan-pl","einlegesohlen_exporte-50400_artisan-yellow-pl","einlegesohlen_exporte-11000_seidl-sensoped-esd-3596-pl","einlegesohlen_exporte-10700_mander-malms-softastatic-sav-02-pl","einlegesohlen_exporte-10800_mander-malms-softastatic-sa-pur-02-pl","einlegesohlen_exporte-10100_esd-pro-pl","einlegesohlen_exporte-50100_sensicare-pl","einlegesohlen_exporte-10600_hartmann-9516-secosol-pl","norm-bezeichnung-en-iso-20345-pl","produktgruppe-trainers-pl","durchtrittschutz_exporte-zadne-pl","zehenschutzkappe_exporte-podnosek-z-metalu-pl","norm-zusaetze-fo-pl","norm-zusaetze-sr-pl"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.9 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EASY blue ESD S1 - 72178 - ELTEN GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EASY blue ESD S1 - 72178\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/\" \/>\n<meta property=\"og:site_name\" content=\"ELTEN GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T10:21:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/\",\"url\":\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/\",\"name\":\"EASY blue ESD S1 - 72178 - ELTEN GmbH\",\"isPartOf\":{\"@id\":\"https:\/\/elten.com\/pl\/#website\"},\"datePublished\":\"2023-09-26T14:06:01+00:00\",\"dateModified\":\"2026-05-07T10:21:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/elten.com\/pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EASY blue ESD S1 &#8211; 72178\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elten.com\/pl\/#website\",\"url\":\"https:\/\/elten.com\/pl\/\",\"name\":\"ELTEN GmbH\",\"description\":\"Sicherheitsschuhe | Arbeitsschuhe | LOWA WORK COLLECTION | ELTEN GmbH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elten.com\/pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EASY blue ESD S1 - 72178 - ELTEN GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/","og_locale":"pl_PL","og_type":"article","og_title":"EASY blue ESD S1 - 72178","og_url":"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/","og_site_name":"ELTEN GmbH","article_modified_time":"2026-05-07T10:21:26+00:00","og_image":[{"url":"https:\/\/elten.com\/wp-content\/uploads\/products\/72178-01.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"3 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/","url":"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/","name":"EASY blue ESD S1 - 72178 - ELTEN GmbH","isPartOf":{"@id":"https:\/\/elten.com\/pl\/#website"},"datePublished":"2023-09-26T14:06:01+00:00","dateModified":"2026-05-07T10:21:26+00:00","breadcrumb":{"@id":"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elten.com\/pl\/products\/easy-blue-esd-s1-72178\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/elten.com\/pl\/"},{"@type":"ListItem","position":2,"name":"EASY blue ESD S1 &#8211; 72178"}]},{"@type":"WebSite","@id":"https:\/\/elten.com\/pl\/#website","url":"https:\/\/elten.com\/pl\/","name":"ELTEN GmbH","description":"Sicherheitsschuhe | Arbeitsschuhe | LOWA WORK COLLECTION | ELTEN GmbH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elten.com\/pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/portfolio\/342715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/comments?post=342715"}],"version-history":[{"count":0,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/portfolio\/342715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/media\/368065"}],"wp:attachment":[{"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/media?parent=342715"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/tags?post=342715"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/portfolio_entries?post=342715"},{"taxonomy":"absatz","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/absatz?post=342715"},{"taxonomy":"dguv","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/dguv?post=342715"},{"taxonomy":"esd","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/esd?post=342715"},{"taxonomy":"farbe","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/farbe?post=342715"},{"taxonomy":"futter","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/futter?post=342715"},{"taxonomy":"geschlecht","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/geschlecht?post=342715"},{"taxonomy":"groesse","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/groesse?post=342715"},{"taxonomy":"metallfrei","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/metallfrei?post=342715"},{"taxonomy":"schuhform","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/schuhform?post=342715"},{"taxonomy":"schutzklasse","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/schutzklasse?post=342715"},{"taxonomy":"tatigkeit","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/tatigkeit?post=342715"},{"taxonomy":"verschluss","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/verschluss?post=342715"},{"taxonomy":"passform_herren_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/passform_herren_exporte?post=342715"},{"taxonomy":"passform_damen_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/passform_damen_exporte?post=342715"},{"taxonomy":"ausstattung_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/ausstattung_exporte?post=342715"},{"taxonomy":"style_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/style_exporte?post=342715"},{"taxonomy":"marke","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/marke?post=342715"},{"taxonomy":"verschluss_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/verschluss_exporte?post=342715"},{"taxonomy":"obermaterial_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/obermaterial_exporte?post=342715"},{"taxonomy":"laufsohlenmaterial_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/laufsohlenmaterial_exporte?post=342715"},{"taxonomy":"einlegesohlen_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/einlegesohlen_exporte?post=342715"},{"taxonomy":"norm-bezeichnung","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/norm-bezeichnung?post=342715"},{"taxonomy":"uidnachhaltig","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/uidnachhaltig?post=342715"},{"taxonomy":"uidsmart","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/uidsmart?post=342715"},{"taxonomy":"uidveredelung","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/uidveredelung?post=342715"},{"taxonomy":"produktgruppe","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/produktgruppe?post=342715"},{"taxonomy":"durchtrittschutz_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/durchtrittschutz_exporte?post=342715"},{"taxonomy":"zehenschutzkappe_exporte","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/zehenschutzkappe_exporte?post=342715"},{"taxonomy":"norm-zusaetze","embeddable":true,"href":"https:\/\/elten.com\/pl\/wp-json\/wp\/v2\/norm-zusaetze?post=342715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}